{"id":41,"count":14,"description":"","link":"https:\/\/lesfemmesrusses.org\/rencontres\/category\/roubaix\/","name":"Roubaix","slug":"roubaix","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/lesfemmesrusses.org\/rencontres\/wp-json\/wp\/v2\/categories\/41"}],"collection":[{"href":"https:\/\/lesfemmesrusses.org\/rencontres\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lesfemmesrusses.org\/rencontres\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lesfemmesrusses.org\/rencontres\/wp-json\/wp\/v2\/posts?categories=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}